{"id":3654,"date":"2021-04-02T18:17:30","date_gmt":"2021-04-02T16:17:30","guid":{"rendered":"https:\/\/sceaux-lagazette.fr\/?p=3654"},"modified":"2021-04-02T21:04:19","modified_gmt":"2021-04-02T19:04:19","slug":"invincible-incivilite","status":"publish","type":"post","link":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/","title":{"rendered":"Invincible incivilit\u00e9 ?"},"content":{"rendered":"\n<p>Petit focus sur un point abord\u00e9 lors de la sixi\u00e8me rencontre \u00ab\u00a0Parlons des Blagis\u00a0\u00bb, le 30 mars. La commissaire de police de Ch\u00e2tenay-Malabry qui \u00e9tait invit\u00e9e a fait une intervention courte et int\u00e9ressante sur la confusion fr\u00e9quente entre incivilit\u00e9 et ins\u00e9curit\u00e9. Elle se r\u00e9f\u00e9rait en cela \u00e0 des interventions qui ont parl\u00e9 parfois de l\u2019un, parfois de l\u2019autre. Pour fixer les id\u00e9es, elle a propos\u00e9 deux d\u00e9finitions. L\u2019incivilit\u00e9, c\u2019est un comportement qui ne respecte pas les r\u00e8gles de vie en commun. L\u2019ins\u00e9curit\u00e9, c\u2019est l\u2019appr\u00e9hension d\u2019\u00eatre victime d\u2019un acte criminel.<\/p>\n\n\n\n<p>Le comportement de certains peut susciter le sentiment d\u2019ins\u00e9curit\u00e9, mais durant ses promenades dans le quartier, non comme polici\u00e8re, mais comme simple quidam, elle ne l\u2019\u00e9prouve jamais. Rien \u00e0 voir, dit-elle, avec les cit\u00e9s dont on parle tant.<\/p>\n\n\n\n<p>Si l\u2019on repense \u00e0 sa distinction, on remarque qu\u2019effectivement, il y a des d\u00e9lits sans incivilit\u00e9, comme des fraudes, des ventes \u00e0 la sauvette. Mais on ne peut pas vraiment dire que des vols ou, pire, des agressions ou des crimes soient de l\u2019incivilit\u00e9. Ou mani\u00e8re de plaisanter. Le deal de drogue, dont plusieurs ont parl\u00e9, m\u00eame s\u2019il est lourd de menaces, n\u2019est pas franchement \u00e0 classer dans les impolitesses. On peut \u00eatre un dealer tr\u00e8s courtois.<\/p>\n\n\n\n<p>Bien s\u00fbr, les menaces, insultes, d\u00e9gradations, squats\u2026 sont \u00e0 la fois des d\u00e9lits et des incivilit\u00e9s. Personne n\u2019a vraiment \u00e9voqu\u00e9 ce type de situations. Si elles se produisent, elles doivent \u00eatre suffisamment rares pour n\u2019avoir pas trouv\u00e9 d\u2019\u00e9cho. Durant les diff\u00e9rentes rencontres, l\u2019ins\u00e9curit\u00e9 (consid\u00e9r\u00e9e comme une crainte de crimes ou d\u00e9lits r\u00e9els) n\u2019est pas apparue comme une caract\u00e9ristique des Blagis.<\/p>\n\n\n\n<p>En revanche, sont revenus assez souvent des abandons d&rsquo;objets dans l&rsquo;espace public (en dehors des poubelles \u00e9videmment), des rassemblements bruyants de jeunes dans les halls d&rsquo;immeubles, les crottes de chien dans le parc des Bas-Coudrais, tous ces petits manques de respect des r\u00e8gles de la vie en soci\u00e9t\u00e9. Le probl\u00e8me est qu\u2019ils ne peuvent pas \u00eatre poursuivis&nbsp;; elles ne constituent pas des infractions au sens du Code p\u00e9nal. Leur r\u00e9p\u00e9tition au quotidien, sans que les institutions (police, justice, mairie) puissent intervenir, les rend d&rsquo;autant plus insupportables.<\/p>\n\n\n\n<p>Il n&rsquo;existe pas de code de la civilit\u00e9 pour r\u00e9gir les relations humaines. Et souvent, plus que de la civilit\u00e9, on attend, on esp\u00e8re de la courtoisie. La confiance entre voisins a plusieurs fois \u00e9t\u00e9 cit\u00e9e comme un \u00e9l\u00e9ment de bien-\u00eatre dans le quartier. On a l\u2019impression que cette qualit\u00e9 des voisinages ne se retrouve pas \u00e0 l\u2019\u00e9chelle du quartier. Toujours est-il que le manque de courtoisie n\u2019est pas un comportement sanctionnable&nbsp;; il ne contrevient \u00e0 aucune interdiction.<\/p>\n\n\n\n<p>Si le constat est souvent partag\u00e9, les avis divergent sur les explications. Deux tendances se sont bien fait sentir parmi les participants. La responsabilit\u00e9 est du c\u00f4t\u00e9 de la mairie ou du bailleur qui ne nettoient pas assez, entretiennent mal. Par ailleurs, les occupations propos\u00e9es aux jeunes sont insuffisantes. Pour les autres, il y va de la responsabilit\u00e9 des individus. L\u2019\u00e9ducation \u00e0 la civilit\u00e9 commence dans les familles&nbsp;; c\u2019est aux gens de ne pas jeter n\u2019importe quoi n\u2019importe o\u00f9.<\/p>\n\n\n\n<p>Il y a ceux pour qui c\u2019est le probl\u00e8me social qui cr\u00e9e les incivilit\u00e9s, en cr\u00e9ant un sentiment d\u2019abandon, de r\u00e9volte. Pour d\u2019autres, les incivilit\u00e9s cr\u00e9ent le probl\u00e8me social et poussent les habitants qui le peuvent \u00e0 quitter le quartier d\u00e8s que possible.<\/p>\n\n\n\n<p>Si le d\u00e9bat s\u2019approfondit, il fera peut-\u00eatre appara\u00eetre des compl\u00e9mentarit\u00e9s entre des positions aujourd\u2019hui \u00e9loign\u00e9es. Pour ne prendre qu\u2019un exemple, jeter ses d\u00e9chets dans l\u2019espace public est l\u2019affaire de chacun et il n\u2019y a pas \u00e0 se d\u00e9fausser. En m\u00eame temps, il revient \u00e0 la collectivit\u00e9 de montrer la voie en renfor\u00e7ant (un temps du moins) le nettoyage pour emp\u00eacher que la malpropret\u00e9 soit consid\u00e9r\u00e9e comme normale.<\/p>\n\n\n\n<p>L\u2019analyse que propose la mairie pour le 1<sup>er<\/sup> juin \u00e9tablira plus s\u00fbrement que ce petit retour comment les sentiments se sont exprim\u00e9s. Citons tout de m\u00eame, pour prendre un peu de recul, un rapport du S\u00e9nat dans lequel on peut reconna\u00eetre bien des propos tenus. Comme quoi, la question n\u2019est pas si particuli\u00e8re aux Blagis. Il y est question de cette incivilit\u00e9 \u00ab&nbsp;qui reste souvent impunie et qui est tr\u00e8s mal v\u00e9cue au quotidien par les citoyens.&nbsp;\u00bb Ce sont ces gestes, \u00ab&nbsp;et non les formes plus graves de d\u00e9linquance, qui \u00ab&nbsp;empoisonnent&nbsp;\u00bb le plus la vie des citoyens aujourd&rsquo;hui et qui sont en grande partie responsables du sentiment d&rsquo;ins\u00e9curit\u00e9.&nbsp;\u00bb<a href=\"#_ftn1\">[1]<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><a href=\"#_ftnref1\">[1]<\/a> Rapport du S\u00e9nat&nbsp;: https:\/\/www.senat.fr\/rap\/r01-340-1\/r01-340-18.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Petit focus sur un point abord\u00e9 lors de la sixi\u00e8me rencontre \u00ab\u00a0Parlons des Blagis\u00a0\u00bb, le 30 mars. La commissaire de police de Ch\u00e2tenay-Malabry qui \u00e9tait invit\u00e9e a fait une intervention courte et int\u00e9ressante sur la confusion fr\u00e9quente entre incivilit\u00e9 et ins\u00e9curit\u00e9. Elle se r\u00e9f\u00e9rait en cela \u00e0 des interventions qui&#8230;<\/p>\n","protected":false},"author":6,"featured_media":3658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[5],"tags":[],"class_list":["post-3654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-des-quartiers-de-sceaux","entry","simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Invincible incivilit\u00e9 ? - La Gazette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Invincible incivilit\u00e9 ? - La Gazette\" \/>\n<meta property=\"og:description\" content=\"Petit focus sur un point abord\u00e9 lors de la sixi\u00e8me rencontre \u00ab\u00a0Parlons des Blagis\u00a0\u00bb, le 30 mars. La commissaire de police de Ch\u00e2tenay-Malabry qui \u00e9tait invit\u00e9e a fait une intervention courte et int\u00e9ressante sur la confusion fr\u00e9quente entre incivilit\u00e9 et ins\u00e9curit\u00e9. Elle se r\u00e9f\u00e9rait en cela \u00e0 des interventions qui&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gazette\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-02T16:17:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-02T19:04:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2175\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maurice Zytnicki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maurice Zytnicki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/\"},\"author\":{\"name\":\"Maurice Zytnicki\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/060ab8fc058c4220d9079707a58da9f1\"},\"headline\":\"Invincible incivilit\u00e9 ?\",\"datePublished\":\"2021-04-02T16:17:30+00:00\",\"dateModified\":\"2021-04-02T19:04:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/\"},\"wordCount\":863,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg\",\"articleSection\":[\"Quartiers\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/\",\"url\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/\",\"name\":\"Invincible incivilit\u00e9 ? - La Gazette\",\"isPartOf\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg\",\"datePublished\":\"2021-04-02T16:17:30+00:00\",\"dateModified\":\"2021-04-02T19:04:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#primaryimage\",\"url\":\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg\",\"contentUrl\":\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg\",\"width\":2175,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/sceaux-lagazette.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Invincible incivilit\u00e9 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#website\",\"url\":\"https:\/\/sceaux-lagazette.fr\/\",\"name\":\"La Gazette\",\"description\":\"Bourg-la-Reine, Ch\u00e2tenay, Fontenay, Sceaux\",\"publisher\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sceaux-lagazette.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#organization\",\"name\":\"La Gazette\",\"url\":\"https:\/\/sceaux-lagazette.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/08\/Logo-Gazette-Aout-2025-V3.jpg\",\"contentUrl\":\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/08\/Logo-Gazette-Aout-2025-V3.jpg\",\"width\":525,\"height\":130,\"caption\":\"La Gazette\"},\"image\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/060ab8fc058c4220d9079707a58da9f1\",\"name\":\"Maurice Zytnicki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d94d30d6fa0e9cb7af48a89366fc0cdb?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d94d30d6fa0e9cb7af48a89366fc0cdb?s=96&r=g\",\"caption\":\"Maurice Zytnicki\"},\"url\":\"https:\/\/sceaux-lagazette.fr\/index.php\/author\/maurice\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Invincible incivilit\u00e9 ? - La Gazette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/","og_locale":"fr_FR","og_type":"article","og_title":"Invincible incivilit\u00e9 ? - La Gazette","og_description":"Petit focus sur un point abord\u00e9 lors de la sixi\u00e8me rencontre \u00ab\u00a0Parlons des Blagis\u00a0\u00bb, le 30 mars. La commissaire de police de Ch\u00e2tenay-Malabry qui \u00e9tait invit\u00e9e a fait une intervention courte et int\u00e9ressante sur la confusion fr\u00e9quente entre incivilit\u00e9 et ins\u00e9curit\u00e9. Elle se r\u00e9f\u00e9rait en cela \u00e0 des interventions qui&#8230;","og_url":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/","og_site_name":"La Gazette","article_published_time":"2021-04-02T16:17:30+00:00","article_modified_time":"2021-04-02T19:04:19+00:00","og_image":[{"width":2175,"height":2560,"url":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg","type":"image\/jpeg"}],"author":"Maurice Zytnicki","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Maurice Zytnicki","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#article","isPartOf":{"@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/"},"author":{"name":"Maurice Zytnicki","@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/060ab8fc058c4220d9079707a58da9f1"},"headline":"Invincible incivilit\u00e9 ?","datePublished":"2021-04-02T16:17:30+00:00","dateModified":"2021-04-02T19:04:19+00:00","mainEntityOfPage":{"@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/"},"wordCount":863,"commentCount":0,"publisher":{"@id":"https:\/\/sceaux-lagazette.fr\/#organization"},"image":{"@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#primaryimage"},"thumbnailUrl":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg","articleSection":["Quartiers"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/","url":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/","name":"Invincible incivilit\u00e9 ? - La Gazette","isPartOf":{"@id":"https:\/\/sceaux-lagazette.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#primaryimage"},"image":{"@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#primaryimage"},"thumbnailUrl":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg","datePublished":"2021-04-02T16:17:30+00:00","dateModified":"2021-04-02T19:04:19+00:00","breadcrumb":{"@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#primaryimage","url":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg","contentUrl":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2021\/04\/Communaute-2-scaled.jpg","width":2175,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2021\/04\/02\/invincible-incivilite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sceaux-lagazette.fr\/"},{"@type":"ListItem","position":2,"name":"Invincible incivilit\u00e9 ?"}]},{"@type":"WebSite","@id":"https:\/\/sceaux-lagazette.fr\/#website","url":"https:\/\/sceaux-lagazette.fr\/","name":"La Gazette","description":"Bourg-la-Reine, Ch\u00e2tenay, Fontenay, Sceaux","publisher":{"@id":"https:\/\/sceaux-lagazette.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sceaux-lagazette.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sceaux-lagazette.fr\/#organization","name":"La Gazette","url":"https:\/\/sceaux-lagazette.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/logo\/image\/","url":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/08\/Logo-Gazette-Aout-2025-V3.jpg","contentUrl":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/08\/Logo-Gazette-Aout-2025-V3.jpg","width":525,"height":130,"caption":"La Gazette"},"image":{"@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/060ab8fc058c4220d9079707a58da9f1","name":"Maurice Zytnicki","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d94d30d6fa0e9cb7af48a89366fc0cdb?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d94d30d6fa0e9cb7af48a89366fc0cdb?s=96&r=g","caption":"Maurice Zytnicki"},"url":"https:\/\/sceaux-lagazette.fr\/index.php\/author\/maurice\/"}]}},"cc_featured_image_caption":{"caption_text":false,"source_text":false,"source_url":false},"_links":{"self":[{"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/posts\/3654"}],"collection":[{"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3654"}],"version-history":[{"count":6,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/posts\/3654\/revisions"}],"predecessor-version":[{"id":3661,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/posts\/3654\/revisions\/3661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/media\/3658"}],"wp:attachment":[{"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}