{"id":1327,"date":"2024-07-23T08:59:17","date_gmt":"2024-07-23T06:59:17","guid":{"rendered":"http:\/\/sceaux-lagazette.fr\/?p=1327"},"modified":"2024-07-23T08:59:18","modified_gmt":"2024-07-23T06:59:18","slug":"le-premier-maire-de-sceaux","status":"publish","type":"post","link":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/","title":{"rendered":"Le premier maire de Sceaux"},"content":{"rendered":"\n<p><strong>Le 7 f\u00e9vrier 1790<\/strong>, les cent vingt-cinq citoyens actifs de Sceaux (sur les quelque 2000 habitants de la paroisse) se r\u00e9unirent en l\u2019\u00e9glise pour<a rel=\"noreferrer noopener\" href=\"https:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k6527179v?rk=21459;2\" target=\"_blank\"> \u00e9lire le premier maire de la ville<\/a>. \u00c9taient citoyens actifs les hommes majeurs, domicili\u00e9s dans le canton et payant une contribution directe correspondant \u00e0 au moins trois jours de travail. La paroisse de Sceaux \u00e9tait auparavant dirig\u00e9e par une assembl\u00e9e \u00e9lue compos\u00e9e de notables et pr\u00e9sid\u00e9e par un syndic.<\/p>\n\n\n\n<p>Le d\u00e9cret du 14 d\u00e9cembre 1789 apporta localement quelques transformations : le syndic est remplac\u00e9 par un maire, \u00e9lu par ses concitoyens, entour\u00e9 d\u2019un procureur syndic et d\u2019un bureau municipal de cinq membres. A cela s\u2019ajoutait un conseil g\u00e9n\u00e9ral de la commune compos\u00e9 de 12 personnes \u00e9galement \u00e9lues.<\/p>\n\n\n\n<p>Si la R\u00e9volution commen\u00e7ante ne bouleversa pas le mode de fonctionnement communal mis en place les derni\u00e8res ann\u00e9es de l\u2019Ancien R\u00e9gime dans les paroisses rurales, elle permit n\u00e9anmoins de porter des hommes nouveaux \u00e0 la t\u00eate du pouvoir local. Richard Glot, \u00e9lu ce 7 f\u00e9vrier 1790, est bien l\u2019un d\u2019entre eux. N\u00e9 \u00e0 Paris en 1740, il se d\u00e9clara \u00ab \u00e9cuyer et fourrier des logis du roy \u00bb sur son acte de <a href=\"https:\/\/archives.sceaux.fr\/sites\/default\/files\/files_d6\/P_GG18_BMS_0.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">mariage \u00e0 Sceaux en 1764<\/a> avec Marie-Genevi\u00e8ve Saug\u00e9.<\/p>\n\n\n\n<p>Il racheta le 29 ao\u00fbt 1772 la manufacture de fa\u00efence de la ville \u00e0 celui qui en avait fait sa gloire, Jacques Chappelle. Glot \u00e9tait un proche du duc de Penthi\u00e8vre, seigneur du domaine de Sceaux, il devint m\u00eame son fond\u00e9 de pouvoir en 1776 et fut charg\u00e9 de percevoir les droits seigneuriaux en 1789. L\u2019homme acquit une renomm\u00e9e nationale quand il protesta, au nom des fa\u00efenciers fran\u00e7ais, contre le trait\u00e9 de libre-\u00e9change conclu en 1786 avec l\u2019Angleterre. D\u2019apr\u00e8s le m\u00e9moire qu\u2019il rendit en 1790, \u00c9tat des manufactures de fa\u00efence et de porcelaine \u00e9tablies dans le royaume, c\u2019est \u00e0 ce trait\u00e9 qu\u2019il faut imputer la grave crise que rencontraient alors les manufactures fran\u00e7aises, min\u00e9es par la concurrence britannique. Les auteurs contemporains nuancent ce jugement(*).<\/p>\n\n\n\n<p>C\u2019est donc sur le propri\u00e9taire d\u2019une manufacture r\u00e9put\u00e9e, sur l\u2019homme de confiance du puissant seigneur local, le duc de Penthi\u00e8vre, et bon connaisseur de la chose locale que se sont port\u00e9 les voix des Sc\u00e9ens. Richard Glot sembla accueillir favorablement les id\u00e9es nouvelles : il fut l\u2019un des r\u00e9dacteurs des<a rel=\"noreferrer noopener\" href=\"https:\/\/www.persee.fr\/doc\/arcpa_0000-0000_1879_num_5_1_2410\" target=\"_blank\"> Cahiers de dol\u00e9ances de la ville<\/a> r\u00e9dig\u00e9s en 1789 et n\u2019h\u00e9sita pas \u00e0 pr\u00e9senter sa candidature en tant que maire.<\/p>\n\n\n\n<p>Son mandat fut toutefois interrompu assez vite lorsque quelques mois apr\u00e8s son \u00e9lection, la commune lui demanda des comptes sur la gestion de la ville. Ce fut une affaire qui demeure obscure pour nous et qui l&rsquo;amena \u00e0 se d\u00e9mettre de son mandat. Comme il avait pris go\u00fbt \u00e0 la chose publique, il remplit d&rsquo;autres fonctions dans l\u2019administration du d\u00e9partement de la Seine. Il demeura n\u00e9anmoins attach\u00e9 \u00e0 Sceaux quelques ann\u00e9es o\u00f9 il commanda la milice municipale durant la p\u00e9riode r\u00e9volutionnaire. On devine que sa bonne fortune dut susciter quelques remous ou quelques envies. Il fut arr\u00eat\u00e9 en l\u2019An II (on ne sait pas exactement la date) et remis en libert\u00e9 en invoquant l\u2019aide de la Soci\u00e9t\u00e9 populaire qui rassemblait les plus ardents r\u00e9volutionnaires.<\/p>\n\n\n\n<p>En 1794, Richard Glot vendit la manufacture \u00e0 Pierre Antoine Cabaret et se retira \u00e0 Versailles o\u00f9 il fut conseiller de pr\u00e9fecture. <a href=\"https:\/\/archives.yvelines.fr\/arkotheque\/visionneuse\/visionneuse.php?arko=YTo2OntzOjQ6ImRhdGUiO3M6MTA6IjIwMjAtMDUtMjkiO3M6MTA6InR5cGVfZm9uZHMiO3M6MTE6ImFya29fc2VyaWVsIjtzOjQ6InJlZjEiO2k6MTtzOjQ6InJlZjIiO2k6NDc5MDtzOjE2OiJ2aXNpb25uZXVzZV9odG1sIjtiOjE7czoyMToidmlzaW9ubmV1c2VfaHRtbF9tb2RlIjtzOjQ6InByb2QiO30=#uielem_move=-22%2C-340&amp;uielem_rotate=F&amp;uielem_islocked=0&amp;uielem_zoom=147\" target=\"_blank\" rel=\"noreferrer noopener\">Il y mourut le 27 septembre 1820<\/a>.<\/p>\n\n\n\n<p><em>Premi\u00e8re publication le 11 juin 2020<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p><strong>Documents cit\u00e9s:<\/strong><br>  &gt; Victor Advielle, Histoire de la ville de Sceaux depuis ses origines jusqu\u2019\u00e0 nos jours, Sceaux\/Paris, Charaire et fils \u00e9diteurs\/A. Picard, 1883<br>  &gt; Archives de Sceaux, Etat civil, mariage de Richard Glot 1764<br>  &gt; Cahier de dol\u00e9ances de Sceaux<br>  &gt; Archives des Yvelines, \u00e9tat civil de Versailles d\u00e9c\u00e8s de Richard Glot, 27 septembre 1820<\/p>\n\n\n\n<p><strong>Pour en savoir plus sur la manufacture de fa\u00efence de Sceaux<br><\/strong>  &gt; Georges Poisson, Maddy Ari\u00e8s, Christian Gautier, Christian B\u00e9alu, Jacques Bastian, Sceaux-Bourg la Reine, <em>150 ans de c\u00e9ramique [catalogue de l&rsquo;exposition du mus\u00e9e de l&rsquo;\u00cele-de-France \u00e0 Sceaux]<\/em>, \u00c9ditions Narboni, 1986<br>  &gt; Fran\u00e7oise Petit, \u00ab Les m\u00e9tiers exerc\u00e9s \u00e0 Sceaux au XVIIIe si\u00e8cle. Le ch\u00e2teau. La manufacture \u00bb, Bulletin des Amis de Sceaux, nouvelle s\u00e9rie, n\u00b0 86, p. 3-28.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 7 f\u00e9vrier 1790, les cent vingt-cinq citoyens actifs de Sceaux (sur les quelque 2000 habitants de la paroisse) se r\u00e9unirent en l\u2019\u00e9glise pour \u00e9lire le premier maire de la ville. \u00c9taient citoyens actifs les hommes majeurs, domicili\u00e9s dans le canton et payant une contribution directe correspondant \u00e0 au moins&#8230;<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[141,266],"tags":[124,208],"class_list":["post-1327","post","type-post","status-publish","format-standard","hentry","category-cette-annee-la","category-sceaux","tag-histoire","tag-maire-de-sceaux","entry","simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le premier maire de Sceaux - La Gazette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le premier maire de Sceaux - La Gazette\" \/>\n<meta property=\"og:description\" content=\"Le 7 f\u00e9vrier 1790, les cent vingt-cinq citoyens actifs de Sceaux (sur les quelque 2000 habitants de la paroisse) se r\u00e9unirent en l\u2019\u00e9glise pour \u00e9lire le premier maire de la ville. \u00c9taient citoyens actifs les hommes majeurs, domicili\u00e9s dans le canton et payant une contribution directe correspondant \u00e0 au moins&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gazette\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-23T06:59:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T06:59:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/12\/Logo-Titre-Gazette-2025-08.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"636\" \/>\n\t<meta property=\"og:image:height\" content=\"148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/\"},\"author\":{\"name\":\"CA\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/210d5f737094760203b063e0887cb530\"},\"headline\":\"Le premier maire de Sceaux\",\"datePublished\":\"2024-07-23T06:59:17+00:00\",\"dateModified\":\"2024-07-23T06:59:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/\"},\"wordCount\":737,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/#organization\"},\"keywords\":[\"Histoire\",\"maire de Sceaux\"],\"articleSection\":[\"Cette ann\u00e9e-l\u00e0\",\"Sceaux\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/\",\"url\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/\",\"name\":\"Le premier maire de Sceaux - La Gazette\",\"isPartOf\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/#website\"},\"datePublished\":\"2024-07-23T06:59:17+00:00\",\"dateModified\":\"2024-07-23T06:59:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/sceaux-lagazette.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le premier maire de Sceaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#website\",\"url\":\"https:\/\/sceaux-lagazette.fr\/\",\"name\":\"La Gazette\",\"description\":\"Bourg-la-Reine, Ch\u00e2tenay, Fontenay, Sceaux\",\"publisher\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sceaux-lagazette.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#organization\",\"name\":\"La Gazette\",\"url\":\"https:\/\/sceaux-lagazette.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/08\/Logo-Gazette-Aout-2025-V3.jpg\",\"contentUrl\":\"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/08\/Logo-Gazette-Aout-2025-V3.jpg\",\"width\":525,\"height\":130,\"caption\":\"La Gazette\"},\"image\":{\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/210d5f737094760203b063e0887cb530\",\"name\":\"CA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c2f3d1c90b4fe3a26691bce97c94e5b8?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c2f3d1c90b4fe3a26691bce97c94e5b8?s=96&r=g\",\"caption\":\"CA\"},\"url\":\"https:\/\/sceaux-lagazette.fr\/index.php\/author\/colette\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le premier maire de Sceaux - La Gazette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Le premier maire de Sceaux - La Gazette","og_description":"Le 7 f\u00e9vrier 1790, les cent vingt-cinq citoyens actifs de Sceaux (sur les quelque 2000 habitants de la paroisse) se r\u00e9unirent en l\u2019\u00e9glise pour \u00e9lire le premier maire de la ville. \u00c9taient citoyens actifs les hommes majeurs, domicili\u00e9s dans le canton et payant une contribution directe correspondant \u00e0 au moins&#8230;","og_url":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/","og_site_name":"La Gazette","article_published_time":"2024-07-23T06:59:17+00:00","article_modified_time":"2024-07-23T06:59:18+00:00","og_image":[{"width":636,"height":148,"url":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/12\/Logo-Titre-Gazette-2025-08.jpg","type":"image\/jpeg"}],"author":"CA","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CA","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/#article","isPartOf":{"@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/"},"author":{"name":"CA","@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/210d5f737094760203b063e0887cb530"},"headline":"Le premier maire de Sceaux","datePublished":"2024-07-23T06:59:17+00:00","dateModified":"2024-07-23T06:59:18+00:00","mainEntityOfPage":{"@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/"},"wordCount":737,"commentCount":0,"publisher":{"@id":"https:\/\/sceaux-lagazette.fr\/#organization"},"keywords":["Histoire","maire de Sceaux"],"articleSection":["Cette ann\u00e9e-l\u00e0","Sceaux"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/","url":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/","name":"Le premier maire de Sceaux - La Gazette","isPartOf":{"@id":"https:\/\/sceaux-lagazette.fr\/#website"},"datePublished":"2024-07-23T06:59:17+00:00","dateModified":"2024-07-23T06:59:18+00:00","breadcrumb":{"@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sceaux-lagazette.fr\/index.php\/2024\/07\/23\/le-premier-maire-de-sceaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sceaux-lagazette.fr\/"},{"@type":"ListItem","position":2,"name":"Le premier maire de Sceaux"}]},{"@type":"WebSite","@id":"https:\/\/sceaux-lagazette.fr\/#website","url":"https:\/\/sceaux-lagazette.fr\/","name":"La Gazette","description":"Bourg-la-Reine, Ch\u00e2tenay, Fontenay, Sceaux","publisher":{"@id":"https:\/\/sceaux-lagazette.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sceaux-lagazette.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sceaux-lagazette.fr\/#organization","name":"La Gazette","url":"https:\/\/sceaux-lagazette.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/logo\/image\/","url":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/08\/Logo-Gazette-Aout-2025-V3.jpg","contentUrl":"https:\/\/sceaux-lagazette.fr\/wp-content\/uploads\/2025\/08\/Logo-Gazette-Aout-2025-V3.jpg","width":525,"height":130,"caption":"La Gazette"},"image":{"@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/210d5f737094760203b063e0887cb530","name":"CA","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sceaux-lagazette.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c2f3d1c90b4fe3a26691bce97c94e5b8?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c2f3d1c90b4fe3a26691bce97c94e5b8?s=96&r=g","caption":"CA"},"url":"https:\/\/sceaux-lagazette.fr\/index.php\/author\/colette\/"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/posts\/1327"}],"collection":[{"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":16,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/posts\/1327\/revisions"}],"predecessor-version":[{"id":41492,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/posts\/1327\/revisions\/41492"}],"wp:attachment":[{"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sceaux-lagazette.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}